{"id":894482,"date":"2024-05-03T10:16:45","date_gmt":"2024-05-03T09:16:45","guid":{"rendered":"https:\/\/www.absaugwerk.de\/8-trabajadores-de-pie-en-el-bosque-%f0%9f%8c%b3\/"},"modified":"2025-12-10T12:57:11","modified_gmt":"2025-12-10T11:57:11","slug":"paseo-de-las-hierbas","status":"publish","type":"post","link":"https:\/\/www.absaugwerk.de\/es\/paseo-de-las-hierbas\/","title":{"rendered":"8 WERKER de pie en el bosque&#8230;\ud83c\udf33"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bb5b35ab4f-bdce-45fd-86b4-d5aa6b9ab1de\u00bb background_enable_color=\u00bboff\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbcff9af7e-a3da-4dd3-83e3-652ffd4dad23&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_post_title _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bb227f5bb6-91a6-49fc-9906-dc7089794df8&#8243; background_enable_image=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_post_title][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb link_option_url_new_window=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<div data-contents=\"true\">\n<div data-contents=\"true\">\n<div class=\"feed-shared-update-v2__description-wrapper mr2\">\n<div class=\"feed-shared-inline-show-more-text feed-shared-update-v2__description feed-shared-inline-show-more-text--minimal-padding feed-shared-inline-show-more-text--3-lines feed-shared-inline-show-more-text--expanded \" style=\"max-height: none;\" data-artdeco-is-focused=\"true\">\n<div class=\"update-components-text relative update-components-update-v2__commentary \" dir=\"ltr\"><span class=\"break-words \"><span dir=\"ltr\">Como parte de nuestras semanas de la salud, el viernes pasado fuimos de excursi\u00f3n a por hierbas a<span class=\"white-space-pre\"> <\/span>Iller<span><\/span><span class=\"white-space-pre\"> <\/span> . La bi\u00f3loga licenciada Sybille R. Braun imparti\u00f3 conocimientos probados sobre el uso y los efectos de nuestras hierbas silvestres y plantas medicinales locales. \ud83c\udf3f<span><br \/><\/span><span class=\"white-space-pre\"> <\/span><span><br \/><\/span>Desde remedios naturales para el resfriado como la ulmaria, la goutweed o la lungwort hasta la poderosa planta ortiga, que contiene pr\u00e1cticamente todos los amino\u00e1cidos esenciales, paseamos por los bosques y prados con los ojos y o\u00eddos bien abiertos y recogimos numerosos consejos para nuestro propio botiqu\u00edn.<span><br \/><\/span><span><br \/><\/span><strong>3 consejos <a class=\"wpil_keyword_link\" href=\"https:\/\/www.absaugwerk.de\/es\/la-empresa\/los-werker\/\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"160911\">WERKER<\/a> de la farmacia del bosque:<\/strong><\/span><\/span><\/div>\n<div class=\"update-components-text relative update-components-update-v2__commentary \" dir=\"ltr\"><span class=\"break-words \"><span dir=\"ltr\">El groundsel \ud83c\udf3f<span><br \/><\/span>Como t\u00e9, tiene un efecto antiinflamatorio, expectorante y cicatrizante. Un consejo para los resfriados o la bronquitis cr\u00f3nica, y no s\u00f3lo en la estaci\u00f3n fr\u00eda. <span><br \/><\/span><span class=\"white-space-pre\"> <\/span><span><br \/><\/span>El tilo \ud83c\udf33<span><br \/><\/span>Sus hojas en infusi\u00f3n fortalecen las c\u00e9lulas y ayudan contra la gripe u otras infecciones v\u00edricas.<span><br \/><\/span><span class=\"white-space-pre\"> <\/span><span><br \/><\/span>La (bardana) paja de la cama \ud83c\udf3f<span><br \/><\/span>Como t\u00e9, puede utilizarse para limpiar la linfa, los ri\u00f1ones o las v\u00edas urinarias y ayuda a desintoxicar el organismo.<span><br \/><\/span><span class=\"white-space-pre\"> <\/span><span><br \/><\/span>Todav\u00eda no estamos<span class=\"white-space-pre\"> <\/span>Bot\u00e1nica<span><\/span><span class=\"white-space-pre\"> <\/span>Profesionales, pero ahora podemos confirmar la afirmaci\u00f3n de Paracelso y Kneipp de que \u00abhay una hierba para cada enfermedad\u00bb.<span><br \/><\/span><span class=\"white-space-pre\"> <\/span><span><br \/><\/span>Sybille no s\u00f3lo da clases en varias escuelas y en la Universidad Popular, sino que tambi\u00e9n ofrece estos paseos guiados por las hierbas individualmente para grupos.<span><br \/><\/span><span class=\"white-space-pre\"> <\/span><span><\/span><span><\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de nuestras semanas de la salud, el viernes pasado fuimos de excursi\u00f3n a por hierbas a Iller . La bi\u00f3loga licenciada Sybille R. Braun imparti\u00f3 conocimientos probados sobre el uso y los efectos de nuestras hierbas silvestres y plantas medicinales locales. \ud83c\udf3f Desde remedios naturales para el resfriado como la ulmaria, la goutweed [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":894485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[143,142],"tags":[],"dipi_cpt_category":[],"class_list":["post-894482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pagina-de-inicio","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/posts\/894482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/comments?post=894482"}],"version-history":[{"count":5,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/posts\/894482\/revisions"}],"predecessor-version":[{"id":1029214,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/posts\/894482\/revisions\/1029214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/media\/894485"}],"wp:attachment":[{"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/media?parent=894482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/categories?post=894482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/tags?post=894482"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/www.absaugwerk.de\/es\/wp-json\/wp\/v2\/dipi_cpt_category?post=894482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}